{"id":30,"date":"2020-10-05T15:19:02","date_gmt":"2020-10-05T13:19:02","guid":{"rendered":"http:\/\/www.caba-non.be\/blog\/?p=30"},"modified":"2020-10-20T11:56:30","modified_gmt":"2020-10-20T09:56:30","slug":"caba-non","status":"publish","type":"post","link":"http:\/\/www.caba-non.be\/blog\/2020\/10\/caba-non\/","title":{"rendered":"Caba-NON!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nous sommes sur les r\u00e9seaux<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.instagram.com\/Collectif.Caba_NON\/?\">Instagram<\/a><\/li><li><a href=\"https:\/\/www.facebook.com\/Collectif.caba.non\/\">Facebook<\/a><\/li><li>Le bon vieil <a href=\"mailto:info@caba-non.be\">e-mail<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Qui sommes-nous?<\/h2>\n\n\n\n<p>Le site Caba-NON! appartient \u00e0 l&rsquo;association herbeumontoise du m\u00eame nom, qui r\u00e9unit de nombreux habitants ayant constat\u00e9 la r\u00e9cente apparition de projets immobiliers de luxe \u00e0 vocation touristique d\u00e9velopp\u00e9s en secret, semble-t-il avec l&rsquo;aval des autorit\u00e9s communales, qui n&rsquo;ont pas jug\u00e9 bon d&rsquo;en informer la population.<br> Ceci a suscit\u00e9 une grande inqui\u00e9tude, car les demandes d\u2019informations furent rejet\u00e9es s\u00e8chement par des phrases comme : \u201cil faut consulter les dossiers \u00e0 la  commune\u201d, \u201cnous ne sommes pas les porteurs du projet\u201d, \u201cnous ne savons rien\u201d. <br> Nous craignons que ces projets d&rsquo;envergure, dans le petit village d&rsquo;Herbeumont, causent de grands dommages \u00e0 la nature, au village lui-m\u00eame, \u00e0 la qualit\u00e9 de vie des habitants.<br> En outre il appara\u00eet que des travaux pr\u00e9paratoires ont \u00e9t\u00e9 entam\u00e9s sur le terrain, avant m\u00eame tout permis d&rsquo;urbanisme!<br> Notre comit\u00e9 d&rsquo;action a donc vu le jour pour s&rsquo;opposer \u00e0 ces projets, car nous sommes convaincus qu&rsquo;il existe de bien meilleures opportunit\u00e9s pour d\u00e9velopper des activit\u00e9s \u00e9conomiques et touristiques \u00e0 Herbeumont. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Objectif<\/h2>\n\n\n\n<p>Ce site sert \u00e0 communiquer au public les informations que nous avons recueillies \u00e0 propos des points suivants :<br> Respect de l&rsquo;esprit de la loi dans le CoDT<br> Protection de la Nature (for\u00eat, faune, eau, sols, \u2026)<\/p>\n\n\n\n<p>Ce site reprend \u00e9galement les contenus de notre feuille de chou, Le Caba-NON!, ainsi que la chronique du V\u00ee Sagl\u00e9, dont nous vous souhaitons bonne lecture.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D&rsquo;o\u00f9 vient le nom du site?<\/h2>\n\n\n\n<p>Caba-NON! d\u00e9rive de l&rsquo;utilisation impropre du mot \u00ab\u00a0cabane\u00a0\u00bb par le promoteur, pour d\u00e9signer des constructions tout confort, en m\u00e9tal bard\u00e9 de bois, reli\u00e9es \u00e0 l&rsquo;eau et l&rsquo;\u00e9lectricit\u00e9, \u00e9quip\u00e9es de pompes \u00e0 chaleur pour le chauffage (et donc aussi l&rsquo;air conditionn\u00e9), ce qui ne correspond pas du tout \u00e0 la d\u00e9finition que nous avons trouv\u00e9e dans le dictionnaire de l&rsquo;Acad\u00e9mie Fran\u00e7aise.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00ab\u00a0CABANE. n. f. Petite maison grossi\u00e8rement construite.\u00a0\u00bb<\/li><\/ul>\n\n\n\n<p>Bref <strong>NON <\/strong>\u00e0 ces pr\u00e9tendues CABAnes!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes sur les r\u00e9seaux Instagram Facebook Le bon vieil e-mail Qui sommes-nous? Le site Caba-NON! appartient \u00e0 l&rsquo;association herbeumontoise du m\u00eame nom, qui r\u00e9unit de nombreux habitants ayant constat\u00e9 la r\u00e9cente apparition de projets immobiliers de luxe \u00e0 vocation touristique d\u00e9velopp\u00e9s en secret, semble-t-il avec l&rsquo;aval des autorit\u00e9s communales, qui n&rsquo;ont pas jug\u00e9 bon &hellip; <a href=\"http:\/\/www.caba-non.be\/blog\/2020\/10\/caba-non\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Caba-NON!&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-30","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/posts\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":3,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/posts\/30\/revisions"}],"predecessor-version":[{"id":205,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/posts\/30\/revisions\/205"}],"wp:attachment":[{"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/media?parent=30"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/categories?post=30"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.caba-non.be\/blog\/wp-json\/wp\/v2\/tags?post=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}